{"id":11,"count":4,"description":"","link":"http:\/\/anoverdetajo.es\/seguridadciudadana\/category\/actos\/","name":"Actos","slug":"actos","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/anoverdetajo.es\/seguridadciudadana\/wp-json\/wp\/v2\/categories\/11"}],"collection":[{"href":"http:\/\/anoverdetajo.es\/seguridadciudadana\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/anoverdetajo.es\/seguridadciudadana\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/anoverdetajo.es\/seguridadciudadana\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}