{"id":496,"date":"2016-04-04T08:54:15","date_gmt":"2016-04-04T07:54:15","guid":{"rendered":"http:\/\/anoverdetajo.es\/infancia\/?p=496"},"modified":"2016-04-04T08:55:42","modified_gmt":"2016-04-04T07:55:42","slug":"nuevo-club-de-lectura-infantil","status":"publish","type":"post","link":"http:\/\/anoverdetajo.es\/infancia\/nuevo-club-de-lectura-infantil\/","title":{"rendered":"Nuevo club de lectura infantil"},"content":{"rendered":"<p style=\"text-align: justify;\">El jueves pasado ha comenzado el Club de Lectura para ni\u00f1os\u00a0en nuestra biblioteca municipal.<!--more--><\/p>\n<p style=\"text-align: justify;\">La idea ha nacido a propuesta de una madre que estaba dispuesta a llevar a su hija lectora a Toledo ante el deseo de la ni\u00f1a de apuntarse a este tipo de actividad. Por el momento ya se han apuntado otros cuatro ni\u00f1os de 7 a\u00f1os (segundo de primaria) que se re\u00fanen todos los jueves de 17 a 18 horas en la biblioteca.<\/p>\n<p style=\"text-align: justify;\">La primera reuni\u00f3n ha comenzado con un breve cuento protagonizado por Ger\u00f3nimo Stilton, adivinanzas y las primeras p\u00e1ginas de Crok, las aventuras de un sapo muy divertido escritas por Fernando Lalana.<\/p>\n<p style=\"text-align: justify;\">Ana Bel\u00e9n Mart\u00edn Padilla, la auxiliar bibliotecaria, es la coordinadora del club e invita a los ni\u00f1os de todas a las edades a sumarse al grupo o a otros que se formen en el futuro. Ana parte de la idea de que \u201cla hora del cuento es un gran divertimento\u201d y por ello quiere que m\u00e1s ni\u00f1os descubran el placer de la lectura.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/aniversario-biblio_0094.jpg\" rel=\"attachment wp-att-497\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-497\" src=\"http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/aniversario-biblio_0094-300x225.jpg\" alt=\"Biblioteca\" width=\"300\" height=\"225\" srcset=\"http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/aniversario-biblio_0094-300x225.jpg 300w, http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/aniversario-biblio_0094-768x576.jpg 768w, http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/aniversario-biblio_0094-1024x768.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jueves pasado ha comenzado el Club de Lectura para ni\u00f1os\u00a0en nuestra biblioteca municipal.<\/p>\n","protected":false},"author":3,"featured_media":498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,1],"tags":[19],"jetpack_featured_media_url":"http:\/\/anoverdetajo.es\/infancia\/wp-content\/uploads\/2016\/04\/crock.jpg","_links":{"self":[{"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/posts\/496"}],"collection":[{"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/comments?post=496"}],"version-history":[{"count":2,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/posts\/496\/revisions"}],"predecessor-version":[{"id":500,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/posts\/496\/revisions\/500"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/media\/498"}],"wp:attachment":[{"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/media?parent=496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/categories?post=496"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/anoverdetajo.es\/infancia\/wp-json\/wp\/v2\/tags?post=496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}